{"id":3,"count":2,"description":"","link":"https:\/\/ent2d.ac-bordeaux.fr\/disciplines\/enseignement-scientifique\/category\/ressources\/","name":"Ressources","slug":"ressources","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/ent2d.ac-bordeaux.fr\/disciplines\/enseignement-scientifique\/wp-json\/wp\/v2\/categories\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ent2d.ac-bordeaux.fr\/disciplines\/enseignement-scientifique\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/ent2d.ac-bordeaux.fr\/disciplines\/enseignement-scientifique\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/ent2d.ac-bordeaux.fr\/disciplines\/enseignement-scientifique\/wp-json\/wp\/v2\/posts?categories=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}