{"id":3805,"date":"2026-02-28T15:05:15","date_gmt":"2026-02-28T14:05:15","guid":{"rendered":"https:\/\/ent2d.ac-bordeaux.fr\/disciplines\/commerce-vente\/?p=3805"},"modified":"2026-02-28T15:05:15","modified_gmt":"2026-02-28T14:05:15","slug":"revue-de-presse-du-01-03-26","status":"publish","type":"post","link":"https:\/\/ent2d.ac-bordeaux.fr\/disciplines\/commerce-vente\/2026\/02\/28\/revue-de-presse-du-01-03-26\/","title":{"rendered":"Revue de presse du 01\/03\/26"},"content":{"rendered":"<div style=\"background-color: #f0f7ff;border-left: 5px solid #005a9c;padding: 15px;margin-bottom: 25px\">\n<p style=\"margin: 0\"><strong>L&#8217;\u00e9dito de la semaine : <\/strong>En route pour une nouvelle p\u00e9riode. Alors que les beau jours reviennent enfin, le rythme reprend de plus belle. Pour vous accompagner, votre revue de presse fait aussi sa rentr\u00e9e&#8230;<\/p>\n<\/div>\n<p><strong>La citation de la semaine :<\/strong><\/p>\n<blockquote>\n<p dir=\"auto\"><em>&#8220;Au march\u00e9, la vente c&#8217;est du th\u00e9\u00e2tre. Le vendeur te hurle dessus, il te lance les fruits&#8230; Si tu n&#8217;as pas l&#8217;impression de te faire engueuler, c&#8217;est que le produit n&#8217;est pas frais. C&#8217;est le seul endroit o\u00f9 l&#8217;agression fait partie du service client.&#8221;<\/em>&#8211; <strong>Redouane Boulgheraba<\/strong><\/p>\n<\/blockquote>\n<p>\u200b<\/p>\n<h2>Divers<\/h2>\n<p><!-- S\u00c9PARATEUR VISUEL --><\/p>\n<hr style=\"border: 0;height: 1px;background-image: linear-gradient(to right, rgba(0, 90, 156, 0), rgba(0, 90, 156, 0.75), rgba(0, 90, 156, 0));margin-top: 10px;margin-bottom: 30px\" \/>\n<p>&nbsp;<\/p>\n<table style=\"width: 100%;border: none;border-collapse: collapse\">\n<tbody>\n<tr><!-- D\u00c9BUT COLONNE DE GAUCHE --><\/p>\n<td style=\"width: 50%;padding-right: 15px;vertical-align: top\">\n<h2>IKEA \/ Decathlon : l&#8217;association qui surprend<\/h2>\n<p>Ikea teste un concept de shop-in-shop avec Decathlon dans son magasin de Croydon, Londres. Decathlon y proposera plus de 5 000 produits sportifs, avec un programme de rachat et un service de Click &amp; Collect. Ce projet s\u2019inscrit dans la strat\u00e9gie d\u2019expansion d\u2019Ikea, visant \u00e0 rendre ses magasins plus accessibles et attrayants.<\/p>\n<p>&nbsp;<\/p>\n<p><a style=\"background-color: #005a9c;color: #ffffff;padding: 10px 15px;text-decoration: none;border-radius: 4px;margin-top: 10px\" href=\"https:\/\/fashionunited.fr\/actualite\/retail\/ikea-va-tester-un-shop-in-shop-decathlon-dans-un-magasin-en-angleterre\/2026022540831\">Lire l&#8217;article complet<\/a><\/td>\n<p><!-- FIN COLONNE DE GAUCHE --><!-- D\u00c9BUT COLONNE DE DROITE --><\/p>\n<td style=\"width: 50%;padding-left: 15px;vertical-align: top\">\n<h3>Kiabi teste un nouveau format &#8220;lieu de vie&#8221; \u00e0 Madrid pour monter en gamme<\/h3>\n<p>Kiabi lance \u00ab La Maison Kiabi \u00bb, un \u00e9v\u00e9nement \u00e9ph\u00e9m\u00e8re \u00e0 Madrid les 27 et 28 f\u00e9vrier, pour renforcer son lien avec les clients. Cet espace lifestyle propose un univers transversal avec des activit\u00e9s vari\u00e9es, du bien-\u00eatre aux ateliers cr\u00e9atifs.<\/p>\n<p>&nbsp;<\/p>\n<p><a style=\"background-color: #005a9c;color: #ffffff;padding: 10px 15px;text-decoration: none;border-radius: 4px;margin-top: 10px\" href=\"https:\/\/fashionunited.fr\/actualite\/retail\/kiabi-mise-sur-levenementiel-avec-le-concept-la-maison-kiabi\/2026022440824\">Lire l&#8217;article complet<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p><!-- SECTION \u00c0 DEUX COLONNES POUR LES ARTICLES --><\/p>\n<table style=\"width: 100%;border: none;border-collapse: collapse\">\n<tbody>\n<tr><!-- COLONNE DE GAUCHE --><\/p>\n<td style=\"width: 50%;padding-right: 15px;vertical-align: top\">\n<h2>Shein persiste et signe<\/h2>\n<p>Shein ouvre des boutiques dans cinq BHV de province, apr\u00e8s le succ\u00e8s controvers\u00e9 de son magasin parisien. Ce d\u00e9ploiement, initialement pr\u00e9vu pour 2025, suscite des critiques pour concurrence d\u00e9loyale et pollution. L\u2019entreprise fait face \u00e0 une pression judiciaire et politique croissante, notamment une enqu\u00eate de l\u2019UE et une demande de blocage de sa marketplace en France.<\/p>\n<p>&nbsp;<\/p>\n<p><a style=\"background-color: #005a9c;color: #ffffff;padding: 10px 15px;text-decoration: none;border-radius: 4px;margin-top: 10px\" href=\"https:\/\/fashionunited.fr\/actualite\/retail\/apres-paris-shein-deploie-ses-boutiques-dans-les-bhv-de-province-ce-mercredi\/2026022440813\">Lire l&#8217;article complet<\/a><\/p>\n<p>&nbsp;<\/td>\n<p><!-- COLONNE DE DROITE --><\/p>\n<td style=\"width: 50%;padding-left: 15px;vertical-align: top\">\n<h3>Les soldes ont elles un avenir ?<\/h3>\n<p>Les soldes d\u2019hiver 2026 ont enregistr\u00e9 une baisse de 0,4 % en valeur par rapport \u00e0 l\u2019ann\u00e9e pr\u00e9c\u00e9dente, confirmant la fin d\u2019un mod\u00e8le commercial obsol\u00e8te. La saturation promotionnelle et la prudence des consommateurs expliquent cette tendance, malgr\u00e9 des taux de d\u00e9marque agressifs.<\/p>\n<p>&nbsp;<\/p>\n<p><a style=\"background-color: #005a9c;color: #ffffff;padding: 10px 15px;text-decoration: none;border-radius: 4px;margin-top: 10px\" href=\"https:\/\/fashionunited.fr\/actualite\/retail\/le-bilan-des-soldes-dhiver-2026-confirme-la-fin-dun-modele-commercial-obsolete\/2026020640674\">Lire l&#8217;article complet<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><!-- S\u00c9PARATEUR VISUEL --><\/p>\n<h2><\/h2>\n<table style=\"width: 100%;border: none;border-collapse: collapse\">\n<tbody>\n<tr><!-- COLONNE DE GAUCHE --><\/p>\n<td style=\"width: 50%;padding-right: 15px;vertical-align: top\">\n<h3>\u00a0L&#8217;IA, nouveau coll\u00e8gue du service logistique ?<\/h3>\n<p>L\u2019IA agentique, capable de prendre des d\u00e9cisions autonomes, transforme la logistique en automatisant les t\u00e2ches r\u00e9p\u00e9titives et lib\u00e9rant les employ\u00e9s pour des t\u00e2ches \u00e0 plus forte valeur ajout\u00e9e. Cependant, l\u2019adoption de l\u2019IA est frein\u00e9e par la qualit\u00e9 des donn\u00e9es, la connectivit\u00e9 r\u00e9seau et la modularit\u00e9 des syst\u00e8mes. La gouvernance est cruciale pour encadrer l\u2019autonomie croissante de l\u2019IA et garantir une utilisation s\u00fbre et efficace.<\/p>\n<p>&nbsp;<\/p>\n<p><a style=\"background-color: #005a9c;color: #ffffff;padding: 10px 15px;text-decoration: none;border-radius: 4px;margin-top: 10px\" href=\"https:\/\/www.lsa-conso.fr\/logistique-quand-l-ia-devient-un-collegue-tribune,464247\">Lire l&#8217;article complet<\/a><\/p>\n<p>&nbsp;<\/td>\n<p><!-- COLONNE DE DROITE --><\/p>\n<td style=\"width: 50%;padding-left: 15px;vertical-align: top\">\n<h3>Quand le hard-discount investit le patrimoine urbain<\/h3>\n<p>Lidl ouvre un magasin XXL de 2 300 m\u00b2 dans l\u2019ancien garage Citro\u00ebn class\u00e9 art d\u00e9co du 7e arrondissement de Lyon, rempla\u00e7ant un ancien supermarch\u00e9 de 700 m\u00b2. Ce projet, en cours depuis plusieurs ann\u00e9es, a n\u00e9cessit\u00e9 pr\u00e8s d\u2019un an de travaux.<\/p>\n<p>&nbsp;<\/p>\n<p><a style=\"background-color: #005a9c;color: #ffffff;padding: 10px 15px;text-decoration: none;border-radius: 4px;margin-top: 10px\" href=\"https:\/\/www.lsa-conso.fr\/lidl-ouvre-un-magasin-xxl-a-lyon-dans-un-monument-historique-classe-et-vise-25-000-clients-par-semaine,464594\">Lire l&#8217;article complet<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><!-- S\u00c9PARATEUR VISUEL --><\/p>\n<hr style=\"border: 0;height: 1px;background-image: linear-gradient(to right, rgba(0, 90, 156, 0), rgba(0, 90, 156, 0.75), rgba(0, 90, 156, 0));margin-top: 10px;margin-bottom: 30px\" \/>\n<p><!-- SECTION \u00c0 DEUX COLONNES POUR LES ARTICLES --><\/p>\n<table style=\"width: 100%;border: none;border-collapse: collapse\">\n<tbody>\n<tr><!-- COLONNE DE GAUCHE --><\/p>\n<td style=\"width: 50%;padding-right: 15px;vertical-align: top\">\n<h3>Quand le luxe s&#8217;offre des magasins ecrins<\/h3>\n<p>Sept concepts de luxe inspirants sont pr\u00e9sent\u00e9s, dont Louis Vuitton avec sa boutique spectaculaire \u00e0 Shanghai, Dior et sa galerie \u00e0 New York, et Loewe avec son identit\u00e9 ancr\u00e9e \u00e0 Tokyo. Pol\u00e8ne, bien que moins prestigieuse, adopte les codes du luxe, tandis que Le Printemps \u00e0 New York et Restoration Hardware \u00e0 Paris mettent l\u2019accent sur l\u2019hospitalit\u00e9 et l\u2019art. Enfin, Jacquemus incarne une version d\u00e9contract\u00e9e du luxe avec ses accessoires de plage.<\/p>\n<p>&nbsp;<\/p>\n<p><a style=\"background-color: #005a9c;color: #ffffff;padding: 10px 15px;text-decoration: none;border-radius: 4px;margin-top: 10px\" href=\"https:\/\/www.lsa-conso.fr\/louis-vuitton-dior-loewe-polene-ces-sept-concepts-de-luxe-hyper-inspirants-reperes-par-la-redaction,464405\">Lire l&#8217;article complet<\/a><\/p>\n<p>&nbsp;<\/td>\n<p><!-- COLONNE DE DROITE --><\/p>\n<td style=\"width: 50%;padding-left: 15px;vertical-align: top\">\n<h3>La confiance, le nouvel enjeu du commerce<\/h3>\n<p>La confiance num\u00e9rique devient une infrastructure strat\u00e9gique, int\u00e9grant identit\u00e9, transactions et conformit\u00e9. L\u2019Europe, avec eIDAS 2.0 et le portefeuille EUDI, avance dans ce domaine, tandis que la fraude et les d\u00e9fis cryptographiques red\u00e9finissent les exigences de s\u00e9curit\u00e9. Six \u00e9volutions majeures sont pr\u00e9vues\u00a0: les portefeuilles num\u00e9riques comme acc\u00e8s universel, l\u2019\u00e9volution vers des attestations de donn\u00e9es, la v\u00e9rification des agents IA, le renforcement de la s\u00e9curit\u00e9, la cryptographie post-quantique et la consolidation des plateformes de confiance.<\/p>\n<p>&nbsp;<\/p>\n<p><a style=\"background-color: #005a9c;color: #ffffff;padding: 10px 15px;text-decoration: none;border-radius: 4px;margin-top: 10px\" href=\"https:\/\/comarketing-news.fr\/la-confiance-numerique-nouvel-enjeu-central-des-annees-a-venir\/\">Lire l&#8217;article complet<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><!-- TITRE DE LA SECONDE CAT\u00c9GORIE --><\/p>\n<h2>IA et \u00e9ducation<\/h2>\n<p><!-- S\u00c9PARATEUR VISUEL --><\/p>\n<hr style=\"border: 0;height: 1px;background-image: linear-gradient(to right, rgba(0, 90, 156, 0), rgba(0, 90, 156, 0.75), rgba(0, 90, 156, 0));margin-top: 10px;margin-bottom: 30px\" \/>\n<p><!-- AUTRE SECTION \u00c0 DEUX COLONNES --><\/p>\n<table style=\"width: 100%;border: none;border-collapse: collapse\">\n<tbody>\n<tr><!-- COLONNE DE GAUCHE --><\/p>\n<td style=\"width: 50%;padding-right: 15px;vertical-align: top\">\n<h3>Exploiter l&#8217;IA dans l&#8217;enseignement : une urgence mise en relief par une forte in\u00e9galit\u00e9<\/h3>\n<p>L\u2019IA g\u00e9n\u00e9rative s\u2019est impos\u00e9e dans l\u2019\u00e9ducation sans d\u00e9bat, avec 80% des \u00e9l\u00e8ves l\u2019utilisant pour leurs devoirs. Les enseignants, quant \u00e0 eux, l\u2019utilisent moins, souvent par manque de temps et de ressources. L\u2019IA peut \u00eatre un outil pr\u00e9cieux pour cr\u00e9er des QCM diff\u00e9renci\u00e9s, mais son utilisation doit respecter les valeurs de l\u2019\u00c9cole et les obligations l\u00e9gales.<\/p>\n<p>&nbsp;<\/p>\n<p><a style=\"background-color: #005a9c;color: #ffffff;padding: 10px 15px;text-decoration: none;border-radius: 4px;margin-top: 10px\" href=\"https:\/\/www.cafepedagogique.net\/2026\/02\/06\/enseignants-et-ia-le-grand-ecart\/\">Lire l&#8217;article complet<\/a><\/td>\n<p><!-- COLONNE DE DROITE --><\/p>\n<td style=\"width: 50%;padding-left: 15px;vertical-align: top\">\n<h3>D\u00e9couvrez ce que propose l&#8217;acad\u00e9mie de Renne autour de l&#8217;IA<\/h3>\n<p>L\u2019intelligence artificielle offre des potentialit\u00e9s extraordinaires pour l\u2019\u00e9ducation, notamment la personnalisation de l\u2019apprentissage, l\u2019automatisation des t\u00e2ches r\u00e9p\u00e9titives, la promotion de l\u2019inclusion et l\u2019engagement des \u00e9l\u00e8ves. Il est crucial pour le monde \u00e9ducatif de se former aux intelligences artificielles.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a style=\"background-color: #005a9c;color: #ffffff;padding: 10px 15px;text-decoration: none;border-radius: 4px;margin-top: 10px\" href=\"https:\/\/pedagogie.ac-rennes.fr\/spip.php?article7774\">Lire l&#8217;article complet<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;\u00e9dito de la semaine : En route pour une nouvelle p\u00e9riode. Alors que les beau jours reviennent enfin, le rythme reprend de plus belle. Pour vous accompagner, votre revue de presse fait aussi sa rentr\u00e9e&#8230; La citation de la semaine : &#8220;Au march\u00e9, la vente c&#8217;est du th\u00e9\u00e2tre. Le vendeur te hurle dessus, il te &hellip; <\/p>\n<p><a class=\"more-link block-button\" href=\"https:\/\/ent2d.ac-bordeaux.fr\/disciplines\/commerce-vente\/2026\/02\/28\/revue-de-presse-du-01-03-26\/\">Lire la Suite &raquo;<\/a><\/p>\n","protected":false},"author":51,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[26],"tags":[30,42,32,72,17,13,63,14,41,15,52,36,79,10,34,66,35,9,33,64,65,21,39,20,46,38,29,22,16],"class_list":["post-3805","post","type-post","status-publish","format-standard","hentry","category-revue-de-presse","tag-academie","tag-actu","tag-actualite","tag-actualite-economique","tag-arcu","tag-bac-pro","tag-bac-pro-mcv","tag-baccalaureat","tag-cap-epc","tag-commerce","tag-commerce-unifie","tag-fmrc","tag-intelligence-artificielle-et-enseignement","tag-lycee-professionnel","tag-mcv","tag-metiers-du-commerce-et-de-la-vente","tag-mrc","tag-nouveaute","tag-omnicanal","tag-option-a","tag-option-b","tag-pedagogie","tag-presse","tag-projet","tag-ressources-pedagogiques","tag-revue","tag-revue-de-presse","tag-tranversal","tag-vente"],"_links":{"self":[{"href":"https:\/\/ent2d.ac-bordeaux.fr\/disciplines\/commerce-vente\/wp-json\/wp\/v2\/posts\/3805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ent2d.ac-bordeaux.fr\/disciplines\/commerce-vente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ent2d.ac-bordeaux.fr\/disciplines\/commerce-vente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ent2d.ac-bordeaux.fr\/disciplines\/commerce-vente\/wp-json\/wp\/v2\/users\/51"}],"replies":[{"embeddable":true,"href":"https:\/\/ent2d.ac-bordeaux.fr\/disciplines\/commerce-vente\/wp-json\/wp\/v2\/comments?post=3805"}],"version-history":[{"count":1,"href":"https:\/\/ent2d.ac-bordeaux.fr\/disciplines\/commerce-vente\/wp-json\/wp\/v2\/posts\/3805\/revisions"}],"predecessor-version":[{"id":3806,"href":"https:\/\/ent2d.ac-bordeaux.fr\/disciplines\/commerce-vente\/wp-json\/wp\/v2\/posts\/3805\/revisions\/3806"}],"wp:attachment":[{"href":"https:\/\/ent2d.ac-bordeaux.fr\/disciplines\/commerce-vente\/wp-json\/wp\/v2\/media?parent=3805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ent2d.ac-bordeaux.fr\/disciplines\/commerce-vente\/wp-json\/wp\/v2\/categories?post=3805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ent2d.ac-bordeaux.fr\/disciplines\/commerce-vente\/wp-json\/wp\/v2\/tags?post=3805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}